{"id":133,"date":"2021-02-03T22:43:22","date_gmt":"2021-02-03T21:43:22","guid":{"rendered":"https:\/\/webilsv2.delixir.com\/blog\/?p=133"},"modified":"2022-03-31T11:25:22","modified_gmt":"2022-03-31T09:25:22","slug":"creation-et-gestion-des-documents","status":"publish","type":"post","link":"https:\/\/webilsv2.delixir.com\/blog\/creation-et-gestion-des-documents-133\/","title":{"rendered":"Cr\u00e9ation et gestion des documents"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Listing des documents<\/h2>\n\n\n\n<p>Rendez-vous dans l&rsquo;onglet \u00ab\u00a0Documents\u00a0\u00bb dans la barre de navigation et choisissez le type de document souhait\u00e9 : <\/p>\n\n\n\n<ul class=\"wp-block-list\" id=\"block-d2d046bc-016a-4a3d-be05-296f927c8c6b\"><li>Devis<\/li><li>Bon de commande<\/li><li>Bon de livraison<\/li><li>Facture (et Avoir)<\/li><\/ul>\n\n\n\n<p>Sur le listing vous retrouverez le commentaire, les champs compl\u00e9mentaires ainsi que les vacations du document. Ces informations sont pliables ou d\u00e9pliables et sont param\u00e9trable depuis <strong>Modules &gt; Soci\u00e9t\u00e9 &gt; Affichage &gt; Section documents<\/strong> si vous disposez des droits ou depuis <strong>Mon compte &gt; Affichage &gt; Section documents<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/webilsv2.delixir.com\/blog\/wp-content\/uploads\/2021\/11\/listing-quotation-1024x632.png\" alt=\"\" class=\"wp-image-4249\" width=\"838\" height=\"517\" srcset=\"https:\/\/webilsv2.delixir.com\/blog\/wp-content\/uploads\/2021\/11\/listing-quotation-1024x632.png 1024w, https:\/\/webilsv2.delixir.com\/blog\/wp-content\/uploads\/2021\/11\/listing-quotation-300x185.png 300w, https:\/\/webilsv2.delixir.com\/blog\/wp-content\/uploads\/2021\/11\/listing-quotation-768x474.png 768w, https:\/\/webilsv2.delixir.com\/blog\/wp-content\/uploads\/2021\/11\/listing-quotation.png 1210w\" sizes=\"auto, (max-width: 838px) 100vw, 838px\" \/><\/figure>\n\n\n\n<p>Vous aurez \u00e9galement la possibilit\u00e9 d&rsquo;exporter des documents :<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"276\" height=\"83\" src=\"https:\/\/webilsv2.delixir.com\/blog\/wp-content\/uploads\/2022\/03\/image-17.png\" alt=\"\" class=\"wp-image-6286\"\/><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Cr\u00e9er un document<\/h2>\n\n\n\n<p>Pour cr\u00e9er un document rendez-vous dans le listing des documents :<\/p>\n\n\n\n<p>Appuyer sur le bouton <img loading=\"lazy\" decoding=\"async\" width=\"220\" height=\"32\" class=\"wp-image-6289\" style=\"width: 220px;\" src=\"https:\/\/webilsv2.delixir.com\/blog\/wp-content\/uploads\/2021\/02\/add-quotation-3.png\" alt=\"\"> pour ajouter un devis, un bon de commande, un bon de livraison ou encore une facture, vous pourrez \u00e9galement exporter les documents.<\/p>\n\n\n\n<p>Une fois le bouton cliqu\u00e9 vous tomberez sur le formulaire ci-dessous :<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/webilsv2.delixir.com\/blog\/wp-content\/uploads\/2021\/02\/add-doc-2021-02-03-113109-1-1024x453.png\" alt=\"\" class=\"wp-image-137\" width=\"718\" height=\"318\" srcset=\"https:\/\/webilsv2.delixir.com\/blog\/wp-content\/uploads\/2021\/02\/add-doc-2021-02-03-113109-1-1024x453.png 1024w, https:\/\/webilsv2.delixir.com\/blog\/wp-content\/uploads\/2021\/02\/add-doc-2021-02-03-113109-1-300x133.png 300w, https:\/\/webilsv2.delixir.com\/blog\/wp-content\/uploads\/2021\/02\/add-doc-2021-02-03-113109-1-768x340.png 768w, https:\/\/webilsv2.delixir.com\/blog\/wp-content\/uploads\/2021\/02\/add-doc-2021-02-03-113109-1.png 1056w\" sizes=\"auto, (max-width: 718px) 100vw, 718px\" \/><\/figure><\/div>\n\n\n\n<ul class=\"wp-block-list\"><li>Vous devrez choisir un client. Si besoin, vous pouvez filtrer par num\u00e9ro ou nom de client.<\/li><li>Puis vous devrez choisir entre ajouter des vacations ou des produits.<\/li><li>Pour finir, vous n&rsquo;aurez plus qu&rsquo;\u00e0 s\u00e9lectionner une ou plusieurs vacations ou un ou plusieurs produits, puis cliquer sur \u00ab\u00a0Passer \u00e0 l&rsquo;\u00e9tape suivante\u00a0\u00bb.<\/li><\/ul>\n\n\n\n<p>Vous allez \u00eatre redirig\u00e9 vers la page ci-dessous :<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/webilsv2.delixir.com\/blog\/wp-content\/uploads\/2021\/02\/add-doc-details-2021-02-03-141459.png\" alt=\"\" class=\"wp-image-142\" width=\"694\" height=\"401\" srcset=\"https:\/\/webilsv2.delixir.com\/blog\/wp-content\/uploads\/2021\/02\/add-doc-details-2021-02-03-141459.png 936w, https:\/\/webilsv2.delixir.com\/blog\/wp-content\/uploads\/2021\/02\/add-doc-details-2021-02-03-141459-300x173.png 300w, https:\/\/webilsv2.delixir.com\/blog\/wp-content\/uploads\/2021\/02\/add-doc-details-2021-02-03-141459-768x444.png 768w\" sizes=\"auto, (max-width: 694px) 100vw, 694px\" \/><\/figure><\/div>\n\n\n\n<p>Sur cette page vous allez pouvoir modifier les informations concernant :<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Le \u00ab\u00a0Client\u00a0\u00bb dont la \u00ab\u00a0Date\u00a0\u00bb du document, l'\u00a0\u00bbAdresse de facturation\u00a0\u00bb, le \u00ab\u00a0Mail\u00a0\u00bb, le \u00ab\u00a0T\u00e9l\u00e9phone\u00a0\u00bb ainsi que le \u00ab\u00a0Mode de r\u00e8glement\u00a0\u00bb.<\/li><li>Les \u00ab\u00a0Vacations\u00a0\u00bb, vous pourrez modifier la vacation, voir le commentaire de celle-ci, la supprimer et la d\u00e9placer gr\u00e2ce aux boutons situ\u00e9s en haut \u00e0 gauche de la vacation comme affich\u00e9 ci-dessous :<\/li><\/ul>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/webilsv2.delixir.com\/blog\/wp-content\/uploads\/2021\/02\/btn-vacation-doc-2021-02-03-143046.png\" alt=\"\" class=\"wp-image-144\" width=\"182\" height=\"46\"\/><\/figure><\/div>\n\n\n\n<p>N&rsquo;oubliez pas de sauvegarder les modifications avec le bouton \u00ab\u00a0Enregistrer\u00a0\u00bb.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Modifier les informations d&rsquo;un document<\/h2>\n\n\n\n<p>Rendez-vous dans le listing de type de document souhait\u00e9.<\/p>\n\n\n\n<p>Cliquez sur le document souhait\u00e9 dans le tableau des documents.<\/p>\n\n\n\n<p>Lorsque vous modifierez un document, de nouvelles options vont s&rsquo;afficher comme ci-dessous :<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"342\" height=\"195\" src=\"https:\/\/webilsv2.delixir.com\/blog\/wp-content\/uploads\/2022\/03\/image-8.png\" alt=\"\" class=\"wp-image-6164\" srcset=\"https:\/\/webilsv2.delixir.com\/blog\/wp-content\/uploads\/2022\/03\/image-8.png 342w, https:\/\/webilsv2.delixir.com\/blog\/wp-content\/uploads\/2022\/03\/image-8-300x171.png 300w\" sizes=\"auto, (max-width: 342px) 100vw, 342px\" \/><\/figure><\/div>\n\n\n\n<p>Vous pourrez :<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>\u00ab\u00a0Ouvrir le PDF\u00a0\u00bb du document.<\/li><li>\u00ab\u00a0Transf\u00e9rer vers le (document) vers\u2026\u00a0\u00bb le document en un autre type de document. Si c&rsquo;est un devis, vous pouvez par exemple le passer en Bon de commande, Bon de livraison ou Facture.<\/li><li>\u00ab\u00a0D\u00e9tacher les vacations s\u00e9lectionn\u00e9es\u00a0\u00bb pour d\u00e9tacher une ou plusieurs vacations vers un nouveau document ou un document existant.<\/li><li>\u00ab\u00a0Ajouter un acompte\u00a0\u00bb pour saisir des arrhes.<\/li><li>\u00ab\u00a0Ajouter une alerte\u00a0\u00bb.<\/li><li>\u00ab\u00a0Copier\u00a0\u00bb le document uniquement disponible sur les devis.<\/li><li>\u00ab\u00a0Supprimer le (document)\u00a0\u00bb, avec la possibilit\u00e9 d&rsquo;annuler les vacations associ\u00e9es.<\/li><li>\u00ab\u00a0Refacturer\u00a0\u00bb pour refacturer une ou plusieurs vacations d&rsquo;un avoir vers une nouvelle facture.<\/li><\/ul>\n\n\n\n<p>Vous pourrez \u00e9galement ajouter ou modifier une adresse administrative ou encore modifier l&rsquo;adresse de facturation et les ajouter au carnet d&rsquo;adresse du client :<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"191\" src=\"https:\/\/webilsv2.delixir.com\/blog\/wp-content\/uploads\/2022\/03\/image-18-1024x191.png\" alt=\"\" class=\"wp-image-6293\" srcset=\"https:\/\/webilsv2.delixir.com\/blog\/wp-content\/uploads\/2022\/03\/image-18-1024x191.png 1024w, https:\/\/webilsv2.delixir.com\/blog\/wp-content\/uploads\/2022\/03\/image-18-300x56.png 300w, https:\/\/webilsv2.delixir.com\/blog\/wp-content\/uploads\/2022\/03\/image-18-768x143.png 768w, https:\/\/webilsv2.delixir.com\/blog\/wp-content\/uploads\/2022\/03\/image-18.png 1252w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Vous pourrez lier des fichiers issus de la \u00ab\u00a0M\u00e9diath\u00e8que\u00a0\u00bb ou ajouter des fichiers \u00e0 ce document via la section suivante :<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/webilsv2.delixir.com\/blog\/wp-content\/uploads\/2021\/02\/docs-doc-2021-02-03-145410-1024x205.png\" alt=\"\" class=\"wp-image-149\" width=\"686\" height=\"137\" srcset=\"https:\/\/webilsv2.delixir.com\/blog\/wp-content\/uploads\/2021\/02\/docs-doc-2021-02-03-145410-1024x205.png 1024w, https:\/\/webilsv2.delixir.com\/blog\/wp-content\/uploads\/2021\/02\/docs-doc-2021-02-03-145410-300x60.png 300w, https:\/\/webilsv2.delixir.com\/blog\/wp-content\/uploads\/2021\/02\/docs-doc-2021-02-03-145410-768x154.png 768w, https:\/\/webilsv2.delixir.com\/blog\/wp-content\/uploads\/2021\/02\/docs-doc-2021-02-03-145410-1110x224.png 1110w, https:\/\/webilsv2.delixir.com\/blog\/wp-content\/uploads\/2021\/02\/docs-doc-2021-02-03-145410.png 1117w\" sizes=\"auto, (max-width: 686px) 100vw, 686px\" \/><\/figure><\/div>\n\n\n\n<p>Et pour finir vous pourrez aussi consulter la vie du document, ses modifications, par l&rsquo;interm\u00e9diaire de la derni\u00e8re section \u00ab\u00a0Historique\u00a0\u00bb :<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/webilsv2.delixir.com\/blog\/wp-content\/uploads\/2021\/02\/history-doc-user-2021-02-03-145909-1024x284.png\" alt=\"\" class=\"wp-image-151\" width=\"689\" height=\"191\" srcset=\"https:\/\/webilsv2.delixir.com\/blog\/wp-content\/uploads\/2021\/02\/history-doc-user-2021-02-03-145909-1024x284.png 1024w, https:\/\/webilsv2.delixir.com\/blog\/wp-content\/uploads\/2021\/02\/history-doc-user-2021-02-03-145909-300x83.png 300w, https:\/\/webilsv2.delixir.com\/blog\/wp-content\/uploads\/2021\/02\/history-doc-user-2021-02-03-145909-768x213.png 768w, https:\/\/webilsv2.delixir.com\/blog\/wp-content\/uploads\/2021\/02\/history-doc-user-2021-02-03-145909.png 1105w\" sizes=\"auto, (max-width: 689px) 100vw, 689px\" \/><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Listing des documents Rendez-vous dans l&rsquo;onglet \u00ab\u00a0Documents\u00a0\u00bb dans la barre de navigation et choisissez le<\/p>\n","protected":false},"author":2,"featured_media":168,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-133","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-documents"],"_links":{"self":[{"href":"https:\/\/webilsv2.delixir.com\/blog\/wp-json\/wp\/v2\/posts\/133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webilsv2.delixir.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/webilsv2.delixir.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/webilsv2.delixir.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/webilsv2.delixir.com\/blog\/wp-json\/wp\/v2\/comments?post=133"}],"version-history":[{"count":62,"href":"https:\/\/webilsv2.delixir.com\/blog\/wp-json\/wp\/v2\/posts\/133\/revisions"}],"predecessor-version":[{"id":6386,"href":"https:\/\/webilsv2.delixir.com\/blog\/wp-json\/wp\/v2\/posts\/133\/revisions\/6386"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/webilsv2.delixir.com\/blog\/wp-json\/wp\/v2\/media\/168"}],"wp:attachment":[{"href":"https:\/\/webilsv2.delixir.com\/blog\/wp-json\/wp\/v2\/media?parent=133"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/webilsv2.delixir.com\/blog\/wp-json\/wp\/v2\/categories?post=133"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/webilsv2.delixir.com\/blog\/wp-json\/wp\/v2\/tags?post=133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}