{"id":4344,"date":"2022-03-23T09:46:01","date_gmt":"2022-03-23T08:46:01","guid":{"rendered":"https:\/\/webilsv2.delixir.com\/blog\/?p=4344"},"modified":"2022-07-11T14:32:29","modified_gmt":"2022-07-11T12:32:29","slug":"creation-et-gestion-des-types-de-vacations","status":"publish","type":"post","link":"https:\/\/webilsv2.delixir.com\/blog\/creation-et-gestion-des-types-de-vacations-4344\/","title":{"rendered":"Cr\u00e9ation et gestion des Types de vacations"},"content":{"rendered":"\n<p>Pour acc\u00e9der aux types de vacation rendez-vous dans Modules &gt; Param\u00e8tres &gt; Types de vacation.<\/p>\n\n\n\n<p>Pour cr\u00e9er un type de vacation cliquez sur <img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"27\" class=\"wp-image-4345\" style=\"width: 120px;\" src=\"https:\/\/webilsv2.delixir.com\/blog\/wp-content\/uploads\/2021\/11\/add-vacation-type.png\" alt=\"\">.<\/p>\n\n\n\n<p>Le formulaire ci-dessous appara\u00eetra :<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/webilsv2.delixir.com\/blog\/wp-content\/uploads\/2021\/11\/add-form-vacation-type-1024x505.png\" alt=\"\" class=\"wp-image-4346\" width=\"835\" height=\"411\" srcset=\"https:\/\/webilsv2.delixir.com\/blog\/wp-content\/uploads\/2021\/11\/add-form-vacation-type-1024x505.png 1024w, https:\/\/webilsv2.delixir.com\/blog\/wp-content\/uploads\/2021\/11\/add-form-vacation-type-300x148.png 300w, https:\/\/webilsv2.delixir.com\/blog\/wp-content\/uploads\/2021\/11\/add-form-vacation-type-768x379.png 768w, https:\/\/webilsv2.delixir.com\/blog\/wp-content\/uploads\/2021\/11\/add-form-vacation-type.png 1340w\" sizes=\"auto, (max-width: 835px) 100vw, 835px\" \/><\/figure><\/div>\n\n\n\n<p>Avec le bouton <img loading=\"lazy\" decoding=\"async\" width=\"27\" height=\"23\" class=\"wp-image-4355\" style=\"width: 27px;\" src=\"https:\/\/webilsv2.delixir.com\/blog\/wp-content\/uploads\/2021\/11\/plus-circle-1.png\" alt=\"\">, vous pourrez associer des produits (produit, prestation et frais) qui vous seront utiles lors de la cr\u00e9ation d&rsquo;une vacation, puisque ces produits seront calcul\u00e9s automatiquement par le logiciel en fonction de la date, du nombre d&rsquo;heures, des intervenants ou encore du lieu de la vacation.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour acc\u00e9der aux types de vacation rendez-vous dans Modules &gt; Param\u00e8tres &gt; Types de vacation.<\/p>\n","protected":false},"author":2,"featured_media":6986,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,9,29],"tags":[],"class_list":["post-4344","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-modules","category-parametres","category-types-de-vacation"],"_links":{"self":[{"href":"https:\/\/webilsv2.delixir.com\/blog\/wp-json\/wp\/v2\/posts\/4344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webilsv2.delixir.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/webilsv2.delixir.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/webilsv2.delixir.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/webilsv2.delixir.com\/blog\/wp-json\/wp\/v2\/comments?post=4344"}],"version-history":[{"count":9,"href":"https:\/\/webilsv2.delixir.com\/blog\/wp-json\/wp\/v2\/posts\/4344\/revisions"}],"predecessor-version":[{"id":4357,"href":"https:\/\/webilsv2.delixir.com\/blog\/wp-json\/wp\/v2\/posts\/4344\/revisions\/4357"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/webilsv2.delixir.com\/blog\/wp-json\/wp\/v2\/media\/6986"}],"wp:attachment":[{"href":"https:\/\/webilsv2.delixir.com\/blog\/wp-json\/wp\/v2\/media?parent=4344"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/webilsv2.delixir.com\/blog\/wp-json\/wp\/v2\/categories?post=4344"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/webilsv2.delixir.com\/blog\/wp-json\/wp\/v2\/tags?post=4344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}